{"id":270,"date":"2023-06-22T16:31:13","date_gmt":"2023-06-22T16:31:13","guid":{"rendered":"https:\/\/proyecto-h.com\/?page_id=270"},"modified":"2025-10-31T16:13:42","modified_gmt":"2025-10-31T16:13:42","slug":"embajadores","status":"publish","type":"page","link":"https:\/\/proyecto-h.com\/en\/embajadores\/","title":{"rendered":"Ambassadors"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"270\" class=\"elementor elementor-270\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-475f421f elementor-section-content-middle elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"475f421f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1915f425\" data-id=\"1915f425\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-754b1864 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"754b1864\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-309464f1\" data-id=\"309464f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-646faedd elementor-align-left elementor-hidden-mobile animated-slow elementor-invisible elementor-widget elementor-widget-button\" data-id=\"646faedd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewbox=\"0 0 54.54 199.09\"><defs><style>.cls-1{fill:none;stroke:#e6e5e5;stroke-miterlimit:10;stroke-width:3px;}.cls-2{fill:#e6e5e5;}<\/style><\/defs><line class=\"cls-1\" x1=\"27.27\" x2=\"27.27\" y2=\"177.73\"><\/line><path class=\"cls-2\" d=\"m27.27,175.31c6.27-6.27,18.67-9.26,27.27-9.5-11.55,8.6-21.62,19.77-27.27,33.28-5.41-13.51-16.09-24.19-27.27-33.28,9.21.74,20.39,2.99,27.27,9.5Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-58365639 elementor-invisible\" data-id=\"58365639\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f494690 elementor-widget elementor-widget-heading\" data-id=\"3f494690\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Project H Ambassadors<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-502365fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"502365fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f93d37\" data-id=\"f93d37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72c918c3 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"72c918c3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">En este espacio exaltaremos los hombres que se han comprometido en Proyecto H. A continuaci\u00f3n aquellos incluidos en los dos libros y los podcast<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e380f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e380f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2e43978\" data-id=\"2e43978\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ef8303 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5ef8303\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Herman-Galan.jpg\" class=\"attachment-full size-full wp-image-782\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Herman-Galan.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Herman-Galan-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Herman-Galan-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Herman-Galan-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Herman-Galan-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Herman Gal\u00e1n<\/h3><p class=\"elementor-image-box-description\">CEO Refiner\u00eda de Cartagena<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d6500a2\" data-id=\"d6500a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-deaef5c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"deaef5c\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Mario-Giraldo.jpg\" class=\"attachment-full size-full wp-image-780\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Mario-Giraldo.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Mario-Giraldo-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Mario-Giraldo-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Mario-Giraldo-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Mario-Giraldo-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Carlos Mario Giraldo<\/h3><p class=\"elementor-image-box-description\">CEO Grupo \u00c9xito<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0490b49\" data-id=\"0490b49\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9d842e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d9d842e\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Luis-Fernando-Perez.jpg\" class=\"attachment-full size-full wp-image-785\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Luis-Fernando-Perez.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Luis-Fernando-Perez-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Luis-Fernando-Perez-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Luis-Fernando-Perez-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Luis-Fernando-Perez-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Luis Fernando P\u00e9rez<\/h3><p class=\"elementor-image-box-description\">Presidente de la C\u00e1mara de Comercio de Cali<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e044861 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e044861\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fde97c3\" data-id=\"fde97c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fb1e80 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1fb1e80\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Mauricio-Ossa.jpg\" class=\"attachment-full size-full wp-image-786\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Mauricio-Ossa.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Mauricio-Ossa-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Mauricio-Ossa-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Mauricio-Ossa-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Mauricio-Ossa-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Mauricio Ossa<\/h3><p class=\"elementor-image-box-description\">Presidente de Odinsa S.A.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f2de602\" data-id=\"f2de602\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c35c0c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8c35c0c\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Esteban-Piedrahita.jpg\" class=\"attachment-full size-full wp-image-781\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Esteban-Piedrahita.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Esteban-Piedrahita-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Esteban-Piedrahita-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Esteban-Piedrahita-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Esteban-Piedrahita-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Esteban Piedrahita<\/h3><p class=\"elementor-image-box-description\">Rector Universidad ICESI<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-afa3f1a\" data-id=\"afa3f1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fc3eef elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5fc3eef\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Juan-Manuel-Rojas.jpg\" class=\"attachment-full size-full wp-image-784\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Juan-Manuel-Rojas.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Juan-Manuel-Rojas-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Juan-Manuel-Rojas-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Juan-Manuel-Rojas-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Juan-Manuel-Rojas-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Juan Manuel Rojas<\/h3><p class=\"elementor-image-box-description\">Presidente de Promigas<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fade2dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fade2dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fcbeb58\" data-id=\"fcbeb58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dceaeb elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5dceaeb\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Jabar-Singh.jpg\" class=\"attachment-full size-full wp-image-783\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Jabar-Singh.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Jabar-Singh-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Jabar-Singh-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Jabar-Singh-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Jabar-Singh-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Jabar Singh<\/h3><p class=\"elementor-image-box-description\">CEO Scotiabank Colpatria<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-46e711c\" data-id=\"46e711c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06b3403 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"06b3403\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Ivan-Villegas.jpg\" class=\"attachment-full size-full wp-image-779\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Ivan-Villegas.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Ivan-Villegas-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Ivan-Villegas-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Ivan-Villegas-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2024\/09\/Carlos-Ivan-Villegas-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Carlos Iv\u00e1n Villegas<\/h3><p class=\"elementor-image-box-description\">CEO Tuya S.A.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-10d6c6a\" data-id=\"10d6c6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-312a0f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"312a0f6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c955347\" data-id=\"c955347\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d5ac7a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2d5ac7a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1281\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Felipe-Bayon-e1687452538686.jpg\" class=\"attachment-full size-full wp-image-282\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Felipe-Bayon-e1687452538686.jpg 1280w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Felipe-Bayon-e1687452538686-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Felipe-Bayon-e1687452538686-1024x1024.jpg 1024w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Felipe-Bayon-e1687452538686-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Felipe-Bayon-e1687452538686-768x769.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Felipe Bay\u00f3n<\/h3><p class=\"elementor-image-box-description\">Member of Directive Boards<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7fc1393\" data-id=\"7fc1393\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6e13b4 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f6e13b4\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1708\" height=\"1707\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Pedro-Felipe-Carvajal-2-scaled-e1687453018813.jpg\" class=\"attachment-full size-full wp-image-296\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Pedro-Felipe-Carvajal-2-scaled-e1687453018813.jpg 1708w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Pedro-Felipe-Carvajal-2-scaled-e1687453018813-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Pedro-Felipe-Carvajal-2-scaled-e1687453018813-1024x1024.jpg 1024w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Pedro-Felipe-Carvajal-2-scaled-e1687453018813-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Pedro-Felipe-Carvajal-2-scaled-e1687453018813-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Pedro-Felipe-Carvajal-2-scaled-e1687453018813-1536x1536.jpg 1536w\" sizes=\"(max-width: 1708px) 100vw, 1708px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pedro Felipe Carvajal<\/h3><p class=\"elementor-image-box-description\">President, Carvajal<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-382b816\" data-id=\"382b816\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d304563 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d304563\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1335\" height=\"1333\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Colmenares-2-e1687453047230.jpg\" class=\"attachment-full size-full wp-image-297\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Colmenares-2-e1687453047230.jpg 1335w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Colmenares-2-e1687453047230-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Colmenares-2-e1687453047230-1024x1022.jpg 1024w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Colmenares-2-e1687453047230-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Colmenares-2-e1687453047230-768x767.jpg 768w\" sizes=\"(max-width: 1335px) 100vw, 1335px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">David Colmenares<\/h3><p class=\"elementor-image-box-description\">Managing Director Allianz LATAM<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e85fd26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e85fd26\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7901b92\" data-id=\"7901b92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ee92c3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0ee92c3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1667\" height=\"1681\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/MIGUEL-CORTES-2-e1687452678229.jpg\" class=\"attachment-full size-full wp-image-285\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/MIGUEL-CORTES-2-e1687452678229.jpg 1667w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/MIGUEL-CORTES-2-e1687452678229-298x300.jpg 298w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/MIGUEL-CORTES-2-e1687452678229-1015x1024.jpg 1015w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/MIGUEL-CORTES-2-e1687452678229-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/MIGUEL-CORTES-2-e1687452678229-768x774.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/MIGUEL-CORTES-2-e1687452678229-1523x1536.jpg 1523w\" sizes=\"(max-width: 1667px) 100vw, 1667px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Miguel Cortes<\/h3><p class=\"elementor-image-box-description\">President, Grupo Bol\u00edvar<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3fdd926\" data-id=\"3fdd926\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd31f87 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"dd31f87\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1662\" height=\"1662\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Escobar-1-e1687453069325.jpg\" class=\"attachment-full size-full wp-image-298\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Escobar-1-e1687453069325.jpg 1662w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Escobar-1-e1687453069325-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Escobar-1-e1687453069325-1024x1024.jpg 1024w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Escobar-1-e1687453069325-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Escobar-1-e1687453069325-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/David-Escobar-1-e1687453069325-1536x1536.jpg 1536w\" sizes=\"(max-width: 1662px) 100vw, 1662px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">David Escobar <\/h3><p class=\"elementor-image-box-description\">Director, Comfama<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6d24b71\" data-id=\"6d24b71\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34b21f0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"34b21f0\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1708\" height=\"1707\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Juan-Carlos-Mora-1-scaled-e1687452641346.jpg\" class=\"attachment-full size-full wp-image-284\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Juan-Carlos-Mora-1-scaled-e1687452641346.jpg 1708w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Juan-Carlos-Mora-1-scaled-e1687452641346-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Juan-Carlos-Mora-1-scaled-e1687452641346-1024x1024.jpg 1024w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Juan-Carlos-Mora-1-scaled-e1687452641346-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Juan-Carlos-Mora-1-scaled-e1687452641346-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Juan-Carlos-Mora-1-scaled-e1687452641346-1536x1536.jpg 1536w\" sizes=\"(max-width: 1708px) 100vw, 1708px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Juan Carlos Mora<\/h3><p class=\"elementor-image-box-description\">President, Bancolombia<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7b4f06 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7b4f06\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cf70012\" data-id=\"cf70012\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9753ee5 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9753ee5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1335\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Jose-Manuel-Restrepo-1-e1687452586416.jpg\" class=\"attachment-full size-full wp-image-283\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Jose-Manuel-Restrepo-1-e1687452586416.jpg 1333w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Jose-Manuel-Restrepo-1-e1687452586416-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Jose-Manuel-Restrepo-1-e1687452586416-1022x1024.jpg 1022w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Jose-Manuel-Restrepo-1-e1687452586416-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Jose-Manuel-Restrepo-1-e1687452586416-768x769.jpg 768w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Jos\u00e9 Manuel Restrepo <\/h3><p class=\"elementor-image-box-description\">Director, University EIA<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5e23686\" data-id=\"5e23686\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2305095 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2305095\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1406\" height=\"1406\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Sergio-Rincon-e1687538776232.jpg\" class=\"attachment-full size-full wp-image-288\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Sergio-Rincon-e1687538776232.jpg 1406w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Sergio-Rincon-e1687538776232-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Sergio-Rincon-e1687538776232-1024x1024.jpg 1024w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Sergio-Rincon-e1687538776232-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Sergio-Rincon-e1687538776232-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Sergio-Rincon-e1687538776232-12x12.jpg 12w\" sizes=\"(max-width: 1406px) 100vw, 1406px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sergio Rinc\u00f3n<\/h3><p class=\"elementor-image-box-description\">President, Bavaria<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f709b30\" data-id=\"f709b30\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06d825c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"06d825c\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1335\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Nicolas-Uribe-5-e1687452704515.jpg\" class=\"attachment-full size-full wp-image-286\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Nicolas-Uribe-5-e1687452704515.jpg 1333w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Nicolas-Uribe-5-e1687452704515-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Nicolas-Uribe-5-e1687452704515-1022x1024.jpg 1022w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Nicolas-Uribe-5-e1687452704515-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Nicolas-Uribe-5-e1687452704515-768x769.jpg 768w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Nicol\u00e1s Uribe <\/h3><p class=\"elementor-image-box-description\">Miembro independiente de Junta Directiva<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24302ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24302ea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-73e94e8\" data-id=\"73e94e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6743026 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6743026\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/German-Arce-Zapata.jpg\" class=\"attachment-full size-full wp-image-1109\" alt=\"German-Arce-Zapata\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/German-Arce-Zapata.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/German-Arce-Zapata-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/German-Arce-Zapata-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/German-Arce-Zapata-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/German-Arce-Zapata-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">German Arce Zapata<\/h3><p class=\"elementor-image-box-description\">Presidente Asofiduciarias\n<br>Miembro Women in Connection<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5aa6789\" data-id=\"5aa6789\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59681ac elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"59681ac\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/David-Bocanument-Trujillo.jpg\" class=\"attachment-full size-full wp-image-1110\" alt=\"David-Bocanument-Trujillo\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/David-Bocanument-Trujillo.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/David-Bocanument-Trujillo-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/David-Bocanument-Trujillo-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/David-Bocanument-Trujillo-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/David-Bocanument-Trujillo-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">David Bocanument Trujillo<\/h3><p class=\"elementor-image-box-description\">Presidente Fondo de Garant\u00edas FGA<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8099090\" data-id=\"8099090\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ec44f8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1ec44f8\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jose-Camilo-Cordoba.jpg\" class=\"attachment-full size-full wp-image-1111\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jose-Camilo-Cordoba.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jose-Camilo-Cordoba-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jose-Camilo-Cordoba-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jose-Camilo-Cordoba-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jose-Camilo-Cordoba-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Jos\u00e9 Camilo C\u00f3rdoba<\/h3><p class=\"elementor-image-box-description\">Director Ejecutivo de Progresa Choc\u00f3<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf53783 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf53783\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a64711b\" data-id=\"a64711b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fae0452 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"fae0452\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Tomas-Andres-Elejalde.jpg\" class=\"attachment-full size-full wp-image-1112\" alt=\"Tomas-Andres-Elejalde\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Tomas-Andres-Elejalde.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Tomas-Andres-Elejalde-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Tomas-Andres-Elejalde-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Tomas-Andres-Elejalde-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Tomas-Andres-Elejalde-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Tom\u00e1s Andr\u00e9s Elejalde<\/h3><p class=\"elementor-image-box-description\">Gerente General  Metro de Medell\u00edn<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-af471be\" data-id=\"af471be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7512a04 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7512a04\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alejandro-Linares.jpg\" class=\"attachment-full size-full wp-image-1113\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alejandro-Linares.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alejandro-Linares-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alejandro-Linares-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alejandro-Linares-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alejandro-Linares-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Alejandro Linares Cantillo<\/h3><p class=\"elementor-image-box-description\">Expresidente y Magistrado de la Corte Constitucional de Colombia<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-016f53b\" data-id=\"016f53b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30d4808 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"30d4808\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Juan-Pablo-Ospina.jpg\" class=\"attachment-full size-full wp-image-1114\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Juan-Pablo-Ospina.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Juan-Pablo-Ospina-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Juan-Pablo-Ospina-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Juan-Pablo-Ospina-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Juan-Pablo-Ospina-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Juan Pablo Ospina Villegas<\/h3><p class=\"elementor-image-box-description\">Presidente Grupo Coremar<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43d12d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43d12d2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-81832bc\" data-id=\"81832bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9b4012 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d9b4012\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alberto-Mario-Rincon.jpg\" class=\"attachment-full size-full wp-image-1118\" alt=\"Alberto-Mario-Rincon\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alberto-Mario-Rincon.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alberto-Mario-Rincon-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alberto-Mario-Rincon-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alberto-Mario-Rincon-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alberto-Mario-Rincon-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Alberto Mario Rinc\u00f3n Angulo<\/h3><p class=\"elementor-image-box-description\">Director General L\u2019Or\u00e9al Colombia<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-014b34b\" data-id=\"014b34b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95acb49 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"95acb49\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Pablo-Santos.jpg\" class=\"attachment-full size-full wp-image-1119\" alt=\"Pablo-Santos\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Pablo-Santos.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Pablo-Santos-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Pablo-Santos-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Pablo-Santos-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Pablo-Santos-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pablo Santos Ramon<\/h3><p class=\"elementor-image-box-description\">Cofundador y CEO de Finaktiva<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bc195c5\" data-id=\"bc195c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a65634 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8a65634\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Hugo-Zurek.jpg\" class=\"attachment-full size-full wp-image-1120\" alt=\"Hugo-Zurek\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Hugo-Zurek.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Hugo-Zurek-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Hugo-Zurek-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Hugo-Zurek-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Hugo-Zurek-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Hugo Zurek<\/h3><p class=\"elementor-image-box-description\">CEO del Grupo Punto Aliado<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c6d9f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c6d9f8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97e460e\" data-id=\"97e460e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e12ea05 elementor-widget elementor-widget-heading\" data-id=\"e12ea05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Embajadores Ecuador<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2fd394 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2fd394\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3c8cba7\" data-id=\"3c8cba7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c48a38 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3c48a38\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Boris-Aguirre.jpg\" class=\"attachment-full size-full wp-image-1124\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Boris-Aguirre.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Boris-Aguirre-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Boris-Aguirre-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Boris-Aguirre-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Boris-Aguirre-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Boris Aguirre<\/h3><p class=\"elementor-image-box-description\">Cofundador Grupo Entregas<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-72df06e\" data-id=\"72df06e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1ed6fd elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a1ed6fd\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Sebastian-Joffre.jpg\" class=\"attachment-full size-full wp-image-1125\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Sebastian-Joffre.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Sebastian-Joffre-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Sebastian-Joffre-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Sebastian-Joffre-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Sebastian-Joffre-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Sebasti\u00e1n Joffre<\/h3><p class=\"elementor-image-box-description\">Presidente de Laboratorios Bag\u00f3<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-54537d0\" data-id=\"54537d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cf9115 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5cf9115\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Guillermo-Lasso.jpg\" class=\"attachment-full size-full wp-image-1126\" alt=\"Guillermo-Lasso\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Guillermo-Lasso.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Guillermo-Lasso-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Guillermo-Lasso-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Guillermo-Lasso-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Guillermo-Lasso-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Guillermo Lasso Alc\u00edvar<\/h3><p class=\"elementor-image-box-description\">Presidente Ejecutivo en Banco Guayaquil<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2edf608 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2edf608\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-67f06e3\" data-id=\"67f06e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a11a88 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0a11a88\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Camilo-Mier.jpg\" class=\"attachment-full size-full wp-image-1127\" alt=\"Camilo-Mier\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Camilo-Mier.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Camilo-Mier-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Camilo-Mier-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Camilo-Mier-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Camilo-Mier-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Camilo Mier<\/h3><p class=\"elementor-image-box-description\">Presidente Mastercard Ecuador<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-efa1b90\" data-id=\"efa1b90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d40c7f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1d40c7f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alfredo-Pena.jpg\" class=\"attachment-full size-full wp-image-1128\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alfredo-Pena.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alfredo-Pena-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alfredo-Pena-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alfredo-Pena-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Alfredo-Pena-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Alfredo Pe\u00f1a Payr\u00f3<\/h3><p class=\"elementor-image-box-description\">Presidente Grupo Graiman<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f47ed20\" data-id=\"f47ed20\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-370e1db elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"370e1db\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Roque-Sevilla.jpg\" class=\"attachment-full size-full wp-image-1129\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Roque-Sevilla.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Roque-Sevilla-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Roque-Sevilla-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Roque-Sevilla-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Roque-Sevilla-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Roque Sevilla Larrea<\/h3><p class=\"elementor-image-box-description\">Presidente Grupo Futuro<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a5c9e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a5c9e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d164b43\" data-id=\"d164b43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-601867f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"601867f\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Vicente-Wong.jpg\" class=\"attachment-full size-full wp-image-1130\" alt=\"Vicente-Wong\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Vicente-Wong.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Vicente-Wong-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Vicente-Wong-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Vicente-Wong-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Vicente-Wong-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Vicente Wong<\/h3><p class=\"elementor-image-box-description\">Presidente Ejecutivo Favorita Fruit\n<br>Presidente de Reybanpac<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-400f23e\" data-id=\"400f23e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f6f5b5 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8f6f5b5\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jorge-Wills.jpg\" class=\"attachment-full size-full wp-image-1131\" alt=\"Jorge-Wills\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jorge-Wills.jpg 900w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jorge-Wills-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jorge-Wills-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jorge-Wills-768x768.jpg 768w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2025\/10\/Jorge-Wills-12x12.jpg 12w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Jorge Andr\u00e9s Wills Ospina<\/h3><p class=\"elementor-image-box-description\">Presidente Ejecutivo de Veris<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fb3bd86\" data-id=\"fb3bd86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d46af3f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d46af3f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-652e666\" data-id=\"652e666\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a260522 elementor-widget elementor-widget-heading\" data-id=\"a260522\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Team CESA Behind this Project <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a930db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a930db\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-48cced0\" data-id=\"48cced0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1dd2f2 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c1dd2f2\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"631\" height=\"631\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-1-e1687453799543.jpg\" class=\"attachment-full size-full wp-image-318\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-1-e1687453799543.jpg 631w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-1-e1687453799543-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-1-e1687453799543-150x150.jpg 150w\" sizes=\"(max-width: 631px) 100vw, 631px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Emilia Restrepo <\/h3><p class=\"elementor-image-box-description\">Director, CESA<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8bfe7f8\" data-id=\"8bfe7f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-997a547 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"997a547\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1031\" height=\"1031\" src=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-e1687453666851.jpg\" class=\"attachment-full size-full wp-image-317\" alt=\"\" srcset=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-e1687453666851.jpg 1031w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-e1687453666851-300x300.jpg 300w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-e1687453666851-1024x1024.jpg 1024w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-e1687453666851-150x150.jpg 150w, https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Alexander-Emilia-y-Maria-e1687453666851-768x768.jpg 768w\" sizes=\"(max-width: 1031px) 100vw, 1031px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Maria Andrea Trujillo and Alexander Guzm\u00e1n<\/h3><p class=\"elementor-image-box-description\">Co-directors, Center for Corporate Governance Studies<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0dc2999\" data-id=\"0dc2999\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nuestros Embajadores En este espacio exaltaremos los hombres que se han comprometido en Proyecto H. A continuaci\u00f3n aquellos incluidos en los dos libros y los podcast Herman Gal\u00e1n CEO Refiner\u00eda de Cartagena Carlos Mario Giraldo CEO Grupo \u00c9xito Luis Fernando P\u00e9rez Presidente de la C\u00e1mara de Comercio de Cali Mauricio Ossa Presidente de Odinsa S.A. &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/proyecto-h.com\/en\/embajadores\/\"> <span class=\"screen-reader-text\">Ambassadors<\/span> Read More &raquo;<\/a><\/p>","protected":false},"author":1,"featured_media":373,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-270","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Embajadores - Proyecto H<\/title>\n<meta name=\"description\" content=\"En este espacio exaltaremos los hombres que se han comprometido en Proyecto H. A continuaci\u00f3n aquellos incluidos en el primer libro y los primeros podcast.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyecto-h.com\/en\/embajadores\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Embajadores - Proyecto H\" \/>\n<meta property=\"og:description\" content=\"En este espacio exaltaremos los hombres que se han comprometido en Proyecto H. A continuaci\u00f3n aquellos incluidos en el primer libro y los primeros podcast.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyecto-h.com\/en\/embajadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyecto H\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T16:13:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Icon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1243\" \/>\n\t<meta property=\"og:image:height\" content=\"1242\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Icon.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proyecto-h.com\\\/embajadores\\\/\",\"url\":\"https:\\\/\\\/proyecto-h.com\\\/embajadores\\\/\",\"name\":\"Embajadores - Proyecto H\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/box5930.temp.domains\\\/~igclared\\\/proyectoh\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proyecto-h.com\\\/embajadores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proyecto-h.com\\\/embajadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proyecto-h.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Icon.jpg\",\"datePublished\":\"2023-06-22T16:31:13+00:00\",\"dateModified\":\"2025-10-31T16:13:42+00:00\",\"description\":\"En este espacio exaltaremos los hombres que se han comprometido en Proyecto H. A continuaci\u00f3n aquellos incluidos en el primer libro y los primeros podcast.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proyecto-h.com\\\/embajadores\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proyecto-h.com\\\/embajadores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/proyecto-h.com\\\/embajadores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proyecto-h.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Icon.jpg\",\"contentUrl\":\"https:\\\/\\\/proyecto-h.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Icon.jpg\",\"width\":1243,\"height\":1242},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proyecto-h.com\\\/embajadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proyecto-h.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embajadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/box5930.temp.domains\\\/~igclared\\\/proyectoh\\\/#website\",\"url\":\"http:\\\/\\\/box5930.temp.domains\\\/~igclared\\\/proyectoh\\\/\",\"name\":\"Proyecto H\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/box5930.temp.domains\\\/~igclared\\\/proyectoh\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/box5930.temp.domains\\\/~igclared\\\/proyectoh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/box5930.temp.domains\\\/~igclared\\\/proyectoh\\\/#organization\",\"name\":\"Proyecto H\",\"url\":\"http:\\\/\\\/box5930.temp.domains\\\/~igclared\\\/proyectoh\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/box5930.temp.domains\\\/~igclared\\\/proyectoh\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/proyecto-h.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-PH-51.png\",\"contentUrl\":\"https:\\\/\\\/proyecto-h.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-PH-51.png\",\"width\":2108,\"height\":394,\"caption\":\"Proyecto H\"},\"image\":{\"@id\":\"http:\\\/\\\/box5930.temp.domains\\\/~igclared\\\/proyectoh\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Embajadores - Proyecto H","description":"En este espacio exaltaremos los hombres que se han comprometido en Proyecto H. A continuaci\u00f3n aquellos incluidos en el primer libro y los primeros podcast.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyecto-h.com\/en\/embajadores\/","og_locale":"en_US","og_type":"article","og_title":"Embajadores - Proyecto H","og_description":"En este espacio exaltaremos los hombres que se han comprometido en Proyecto H. A continuaci\u00f3n aquellos incluidos en el primer libro y los primeros podcast.","og_url":"https:\/\/proyecto-h.com\/en\/embajadores\/","og_site_name":"Proyecto H","article_modified_time":"2025-10-31T16:13:42+00:00","og_image":[{"width":1243,"height":1242,"url":"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Icon.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Icon.jpg","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/proyecto-h.com\/embajadores\/","url":"https:\/\/proyecto-h.com\/embajadores\/","name":"Embajadores - Proyecto H","isPartOf":{"@id":"http:\/\/box5930.temp.domains\/~igclared\/proyectoh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proyecto-h.com\/embajadores\/#primaryimage"},"image":{"@id":"https:\/\/proyecto-h.com\/embajadores\/#primaryimage"},"thumbnailUrl":"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Icon.jpg","datePublished":"2023-06-22T16:31:13+00:00","dateModified":"2025-10-31T16:13:42+00:00","description":"En este espacio exaltaremos los hombres que se han comprometido en Proyecto H. A continuaci\u00f3n aquellos incluidos en el primer libro y los primeros podcast.","breadcrumb":{"@id":"https:\/\/proyecto-h.com\/embajadores\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyecto-h.com\/embajadores\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/proyecto-h.com\/embajadores\/#primaryimage","url":"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Icon.jpg","contentUrl":"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/Icon.jpg","width":1243,"height":1242},{"@type":"BreadcrumbList","@id":"https:\/\/proyecto-h.com\/embajadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proyecto-h.com\/"},{"@type":"ListItem","position":2,"name":"Embajadores"}]},{"@type":"WebSite","@id":"http:\/\/box5930.temp.domains\/~igclared\/proyectoh\/#website","url":"http:\/\/box5930.temp.domains\/~igclared\/proyectoh\/","name":"Proyecto H","description":"","publisher":{"@id":"http:\/\/box5930.temp.domains\/~igclared\/proyectoh\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/box5930.temp.domains\/~igclared\/proyectoh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/box5930.temp.domains\/~igclared\/proyectoh\/#organization","name":"Proyecto H","url":"http:\/\/box5930.temp.domains\/~igclared\/proyectoh\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/box5930.temp.domains\/~igclared\/proyectoh\/#\/schema\/logo\/image\/","url":"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/cropped-PH-51.png","contentUrl":"https:\/\/proyecto-h.com\/wp-content\/uploads\/2023\/06\/cropped-PH-51.png","width":2108,"height":394,"caption":"Proyecto H"},"image":{"@id":"http:\/\/box5930.temp.domains\/~igclared\/proyectoh\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/proyecto-h.com\/en\/wp-json\/wp\/v2\/pages\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyecto-h.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/proyecto-h.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/proyecto-h.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/proyecto-h.com\/en\/wp-json\/wp\/v2\/comments?post=270"}],"version-history":[{"count":20,"href":"https:\/\/proyecto-h.com\/en\/wp-json\/wp\/v2\/pages\/270\/revisions"}],"predecessor-version":[{"id":1137,"href":"https:\/\/proyecto-h.com\/en\/wp-json\/wp\/v2\/pages\/270\/revisions\/1137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyecto-h.com\/en\/wp-json\/wp\/v2\/media\/373"}],"wp:attachment":[{"href":"https:\/\/proyecto-h.com\/en\/wp-json\/wp\/v2\/media?parent=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}